{"id":83072,"date":"2018-04-26T18:15:36","date_gmt":"2018-04-26T18:15:36","guid":{"rendered":"http:\/\/www.irdin.org.br\/site\/produto\/sinais-de-alerta-e-energia-monastica-em-tempos-de-caos\/"},"modified":"2025-03-15T22:38:09","modified_gmt":"2025-03-15T22:38:09","slug":"sinais-de-alerta-e-energia-monastica-em-tempos-de-caos","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/sinais-de-alerta-e-energia-monastica-em-tempos-de-caos\/","title":{"rendered":"Sinais de alerta e energia mon\u00e1stica em tempos de caos"},"content":{"rendered":"<p><em>A prem\u00eancia de que hoje se assuma a manuten\u00e7\u00e3o do pr\u00f3prio equil\u00edbrio, o que n\u00e3o depende de nada material, e o papel de um Monast\u00e9rio na presente situa\u00e7\u00e3o planet\u00e1ria.<\/em><\/p>\n<p>&nbsp;<br \/>\n<strong>Ou\u00e7a agora:<\/strong><\/p>\n<p><span data-href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0021_0011__por_por__sinais_de_alerta_e_energia_monastica_em_tempos_de_caos.mp3\" data-title=\"sinais de alerta e energia mon\u00e1stica em tempos de caos\" data-rel=\"\" data-target=\"\" data-meta=\"#fap-meta-6a04cce57afb1\" class=\"fap-single-track fap-track-button fap-play-button\" data-enqueue=\"no\" data-autoenqueue=\"no\" title=\"sinais de alerta e energia mon\u00e1stica em tempos de caos\"><span class=\"fap-icon-play\"><\/span>Ouvir<\/span> <a href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0021_0011__por_por__sinais_de_alerta_e_energia_monastica_em_tempos_de_caos.mp3\" class=\"baixar\" download><span class=\"fa fa-arrow-down\"><\/span>Baixar<\/span><\/a> <span class=\"textobaixar\"> sinais de alerta e energia mon\u00e1stica em tempos de caos<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prem\u00eancia de que hoje se assuma a manuten\u00e7\u00e3o do pr\u00f3prio equil\u00edbrio, o que n\u00e3o depende de nada material, e<\/p>\n","protected":false},"featured_media":37803,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18076,33068],"product_tag":[39481],"class_list":{"0":"post-83072","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cddvd","7":"product_cat-palestras","8":"product_tag-39481","9":"pa_autor-trigueirinho","10":"pa_codigo-da-serie-32805","11":"pa_codigo-externo-00210011porcd","12":"pa_data-de-gravacao-20566","13":"pa_duracao-37min","14":"pa_idioma-de-destino-portugues","15":"pa_idioma-de-origem-portugues","16":"pa_lancamento-no","17":"pa_midia-cd","18":"pa_moac-39480","19":"pa_quantidade-de-saldo-33067","20":"pa_sequencial-da-serie-31891","21":"pa_tipo-de-traducao-nao-classificado","23":"first","24":"outofstock","25":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83072\/revisions"}],"predecessor-version":[{"id":109088,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83072\/revisions\/109088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/37803"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=83072"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=83072"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=83072"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=83072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}