{"id":83806,"date":"2018-04-26T18:27:16","date_gmt":"2018-04-26T18:27:16","guid":{"rendered":"http:\/\/www.irdin.org.br\/site\/produto\/de-um-grande-silencio-a-energia-da-vontade\/"},"modified":"2025-03-15T19:23:28","modified_gmt":"2025-03-15T19:23:28","slug":"de-um-grande-silencio-a-energia-da-vontade","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/de-um-grande-silencio-a-energia-da-vontade\/","title":{"rendered":"De um grande sil\u00eancio \u00e0 energia da Vontade"},"content":{"rendered":"<p><em>Filme O grande sil\u00eancio\u00b4 \/ Ora\u00e7\u00e3o operativa segundo Thaykhuma \/ Grupo operativo no deserto de Gobi \/ Que a vontade de Deus se fa\u00e7a                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                               \u00b4<\/em><\/p>\n<p>&nbsp;<br \/>\n<strong>Ou\u00e7a agora:<\/strong><\/p>\n<p><span data-href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0056_0011__por_por__de_um_grande_silencio_a_energia_da_vontade.mp3\" data-title=\"de um grande sil\u00eancio \u00e0 energia da vontade\" data-rel=\"\" data-target=\"\" data-meta=\"#fap-meta-6a04d1dff3c32\" class=\"fap-single-track fap-track-button fap-play-button\" data-enqueue=\"no\" data-autoenqueue=\"no\" title=\"de um grande sil\u00eancio \u00e0 energia da vontade\"><span class=\"fap-icon-play\"><\/span>Ouvir<\/span> <a href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0056_0011__por_por__de_um_grande_silencio_a_energia_da_vontade.mp3\" class=\"baixar\" download><span class=\"fa fa-arrow-down\"><\/span>Baixar<\/span><\/a> <span class=\"textobaixar\"> de um grande sil\u00eancio \u00e0 energia da vontade<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Filme O grande sil\u00eancio\u00b4 \/ Ora\u00e7\u00e3o operativa segundo Thaykhuma \/ Grupo operativo no deserto de Gobi \/ Que a vontade<\/p>\n","protected":false},"featured_media":37803,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18076,33068],"product_tag":[40913],"class_list":{"0":"post-83806","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cddvd","7":"product_cat-palestras","8":"product_tag-40913","9":"pa_autor-trigueirinho","10":"pa_codigo-da-serie-32837","11":"pa_codigo-externo-00560011porcd","12":"pa_data-de-gravacao-31611","13":"pa_duracao-55min57s","14":"pa_idioma-de-destino-portugues","15":"pa_idioma-de-origem-portugues","16":"pa_lancamento-no","17":"pa_midia-cd","18":"pa_moac-40912","19":"pa_quantidade-de-saldo-33067","20":"pa_sequencial-da-serie-31891","21":"pa_tipo-de-traducao-nao-classificado","23":"first","24":"outofstock","25":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83806\/revisions"}],"predecessor-version":[{"id":108458,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83806\/revisions\/108458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/37803"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=83806"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=83806"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=83806"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=83806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}