{"id":83839,"date":"2018-04-26T18:27:56","date_gmt":"2018-04-26T18:27:56","guid":{"rendered":"http:\/\/www.irdin.org.br\/site\/produto\/os-sete-compromissos-para-a-uniao-com-o-cosmos\/"},"modified":"2025-03-15T19:12:59","modified_gmt":"2025-03-15T19:12:59","slug":"os-sete-compromissos-para-a-uniao-com-o-cosmos","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/os-sete-compromissos-para-a-uniao-com-o-cosmos\/","title":{"rendered":"Os sete compromissos para a uni\u00e3o com o Cosmos"},"content":{"rendered":"<p><em>Decidir-se pelo caminho do despertar \/ Em busca de uma vida maior \/ Nossa liga\u00e7\u00e3o com o materialismo \/ Posi\u00e7\u00e3o diante dos movimentos contr\u00e1rios \u00e0 evolu\u00e7\u00e3o \/ Trabalhar pela unidade entre as almas \/ Abrir as portas para o futuro c\u00f3smico<\/em><\/p>\n<p>&nbsp;<br \/>\n<strong>Ou\u00e7a agora:<\/strong><\/p>\n<p><span data-href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0060_0010__por_por__os_sete_compromissos_para_a_uniao_com_o_cosmos.mp3\" data-title=\"os sete compromissos para a uni\u00e3o com o cosmos\" data-rel=\"\" data-target=\"\" data-meta=\"#fap-meta-6a040ae04c9fe\" class=\"fap-single-track fap-track-button fap-play-button\" data-enqueue=\"no\" data-autoenqueue=\"no\" title=\"os sete compromissos para a uni\u00e3o com o cosmos\"><span class=\"fap-icon-play\"><\/span>Ouvir<\/span> <a href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0060_0010__por_por__os_sete_compromissos_para_a_uniao_com_o_cosmos.mp3\" class=\"baixar\" download><span class=\"fa fa-arrow-down\"><\/span>Baixar<\/span><\/a> <span class=\"textobaixar\"> os sete compromissos para a uni\u00e3o com o cosmos<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decidir-se pelo caminho do despertar \/ Em busca de uma vida maior \/ Nossa liga\u00e7\u00e3o com o materialismo \/ Posi\u00e7\u00e3o<\/p>\n","protected":false},"featured_media":37803,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18076,33068],"product_tag":[40979],"class_list":{"0":"post-83839","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cddvd","7":"product_cat-palestras","8":"product_tag-40979","9":"pa_autor-trigueirinho","10":"pa_codigo-da-serie-32842","11":"pa_data-de-gravacao-31788","12":"pa_idioma-de-destino-portugues","13":"pa_lancamento-no","14":"pa_midia-cd","15":"pa_moac-40978","16":"pa_quantidade-de-saldo-33067","17":"pa_sequencial-da-serie-31890","18":"pa_tipo-de-traducao-nao-classificado","20":"first","21":"outofstock","22":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83839\/revisions"}],"predecessor-version":[{"id":108412,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83839\/revisions\/108412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/37803"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=83839"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=83839"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=83839"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=83839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}