{"id":83840,"date":"2018-04-26T18:27:56","date_gmt":"2018-04-26T18:27:56","guid":{"rendered":"http:\/\/www.irdin.org.br\/site\/produto\/nossos-compromissos-com-a-irmandade-branca-1\/"},"modified":"2025-03-15T19:13:08","modified_gmt":"2025-03-15T19:13:08","slug":"nossos-compromissos-com-a-irmandade-branca-1","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/nossos-compromissos-com-a-irmandade-branca-1\/","title":{"rendered":"Nossos compromissos com a Irmandade Branca &#8211; 1"},"content":{"rendered":"<p><em>Nada representamos para o Universo se n\u00e3o vivemos a Lei da Hierarquia \/ Ser fiel no que \u00e9 pequeno para depois ser fiel no que \u00e9 grande \/ Nutrir a pr\u00f3pria consci\u00eancia de vibra\u00e7\u00f5es positivas \/ Manter neutralidade inalter\u00e1vel diante dos desencontros da vida<\/em><\/p>\n<p>&nbsp;<br \/>\n<strong>Ou\u00e7a agora:<\/strong><\/p>\n<p><span data-href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0060_0011__por_por__nossos_compromissos_com_a_irmandade_branca.mp3\" data-title=\"nossos compromissos com a irmandade branca - 1\" data-rel=\"\" data-target=\"\" data-meta=\"#fap-meta-6a03f7cdac16e\" class=\"fap-single-track fap-track-button fap-play-button\" data-enqueue=\"no\" data-autoenqueue=\"no\" title=\"nossos compromissos com a irmandade branca - 1\"><span class=\"fap-icon-play\"><\/span>Ouvir<\/span> <a href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0060_0011__por_por__nossos_compromissos_com_a_irmandade_branca.mp3\" class=\"baixar\" download><span class=\"fa fa-arrow-down\"><\/span>Baixar<\/span><\/a> <span class=\"textobaixar\"> nossos compromissos com a irmandade branca &#8211; 1<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nada representamos para o Universo se n\u00e3o vivemos a Lei da Hierarquia \/ Ser fiel no que \u00e9 pequeno para<\/p>\n","protected":false},"featured_media":37803,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18076,33068],"product_tag":[40981],"class_list":{"0":"post-83840","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cddvd","7":"product_cat-palestras","8":"product_tag-40981","9":"pa_autor-trigueirinho","10":"pa_codigo-da-serie-32842","11":"pa_data-de-gravacao-31791","12":"pa_idioma-de-destino-portugues","13":"pa_lancamento-no","14":"pa_midia-cd","15":"pa_moac-40980","16":"pa_quantidade-de-saldo-33067","17":"pa_sequencial-da-serie-31891","18":"pa_tipo-de-traducao-nao-classificado","20":"first","21":"outofstock","22":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83840\/revisions"}],"predecessor-version":[{"id":108413,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83840\/revisions\/108413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/37803"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=83840"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=83840"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=83840"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=83840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}