{"id":83851,"date":"2018-04-26T18:27:56","date_gmt":"2018-04-26T18:27:56","guid":{"rendered":"http:\/\/www.irdin.org.br\/site\/produto\/alem-do-amor-humano-uma-instrucao-de-amahj\/"},"modified":"2025-03-15T19:17:05","modified_gmt":"2025-03-15T19:17:05","slug":"alem-do-amor-humano-uma-instrucao-de-amhaj","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/alem-do-amor-humano-uma-instrucao-de-amhaj\/","title":{"rendered":"Al\u00e9m do amor humano &#8211; Uma instru\u00e7\u00e3o de Amhaj"},"content":{"rendered":"<p><em>O mal que ataca a Terra neste momento s\u00f3 pode ser resolvido pela for\u00e7a do Esp\u00edrito \/ De onde prov\u00e9m o bem e o amor? \/ O potencial escondido em nossos seres \/ Sem sustenta\u00e7\u00e3o interior n\u00e3o nos sustentaremos durante a transi\u00e7\u00e3o planet\u00e1ria \/ Em um momento pode-se dar um passo definitivo ou colocar tudo a perder<\/em><\/p>\n<p>&nbsp;<br \/>\n<strong>Ou\u00e7a agora:<\/strong><\/p>\n<p><span data-href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0061_0016__por_por__alem_do_amor_humano.mp3\" data-title=\"al\u00e9m do amor humano\" data-rel=\"\" data-target=\"\" data-meta=\"#fap-meta-6a570a7058e92\" class=\"fap-single-track fap-track-button fap-play-button\" data-enqueue=\"no\" data-autoenqueue=\"no\" title=\"al\u00e9m do amor humano\"><span class=\"fap-icon-play\"><\/span>Ouvir<\/span> <a href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0061_0016__por_por__alem_do_amor_humano.mp3\" class=\"baixar\" download><span class=\"fa fa-arrow-down\"><\/span>Baixar<\/span><\/a> <span class=\"textobaixar\"> al\u00e9m do amor humano<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mal que ataca a Terra neste momento s\u00f3 pode ser resolvido pela for\u00e7a do Esp\u00edrito \/ De onde prov\u00e9m<\/p>\n","protected":false},"featured_media":37803,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18076,33068],"product_tag":[41003],"class_list":["post-83851","product","type-product","status-publish","has-post-thumbnail","product_cat-cddvd","product_cat-palestras","product_tag-41003","pa_autor-trigueirinho","pa_codigo-da-serie-31868","pa_codigo-externo-00610016porcd","pa_data-de-gravacao-25361","pa_duracao-68-min","pa_idioma-de-destino-portugues","pa_idioma-de-origem-portugues","pa_lancamento-no","pa_midia-cd","pa_moac-41002","pa_quantidade-de-saldo-33067","pa_sequencial-da-serie-31869","pa_tipo-de-traducao-nao-classificado","first","outofstock","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83851\/revisions"}],"predecessor-version":[{"id":107910,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/83851\/revisions\/107910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/37803"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=83851"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=83851"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=83851"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=83851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}