{"id":84546,"date":"2018-04-26T18:40:20","date_gmt":"2018-04-26T18:40:20","guid":{"rendered":"http:\/\/www.irdin.org.br\/site\/produto\/nossos-sentidos-e-nossas-polaridades\/"},"modified":"2024-09-23T03:15:28","modified_gmt":"2024-09-23T03:15:28","slug":"nossos-sentidos-e-nossas-polaridades","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/nossos-sentidos-e-nossas-polaridades\/","title":{"rendered":"Nossos sentidos e nossas polaridades"},"content":{"rendered":"<p><em>Como o amor \u00e0 Hierarquia Espiritual refina nossos sentidos internos e como se d\u00e1 o influxo da energia feminina no planeta nesta \u00e9poca.<\/em><\/p>\n<p>&nbsp;<br \/>\n<strong>Ou\u00e7a agora:<\/strong><\/p>\n<p><span data-href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0014_0172__por_por__nossos_sentidos_e_nossas_polaridades.mp3\" data-title=\"nossos sentidos e nossas polaridades\" data-rel=\"\" data-target=\"\" data-meta=\"#fap-meta-6a98b0f61324e\" class=\"fap-single-track fap-track-button fap-play-button\" data-enqueue=\"no\" data-autoenqueue=\"no\" title=\"nossos sentidos e nossas polaridades\"><span class=\"fap-icon-play\"><\/span>Ouvir<\/span> <a href=\"https:\/\/www.irdin.org.br\/site\/envios\/audios\/0014_0172__por_por__nossos_sentidos_e_nossas_polaridades.mp3\" class=\"baixar\" download><span class=\"fa fa-arrow-down\"><\/span>Baixar<\/span><\/a> <span class=\"textobaixar\"> nossos sentidos e nossas polaridades<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como o amor \u00e0 Hierarquia Espiritual refina nossos sentidos internos e como se d\u00e1 o influxo da energia feminina no<\/p>\n","protected":false},"featured_media":37803,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18076,33068],"product_tag":[42393],"class_list":["post-84546","product","type-product","status-publish","has-post-thumbnail","product_cat-cddvd","product_cat-palestras","product_tag-42393","pa_autor-trigueirinho","pa_codigo-da-serie-32103","pa_codigo-externo-00140172porcd","pa_data-de-gravacao-18871","pa_duracao-43min","pa_idioma-de-destino-portugues","pa_idioma-de-origem-portugues","pa_lancamento-no","pa_midia-cd","pa_moac-42392","pa_quantidade-de-saldo-33067","pa_sequencial-da-serie-32336","pa_tipo-de-traducao-nao-classificado","first","outofstock","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/84546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/84546\/revisions"}],"predecessor-version":[{"id":107457,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/84546\/revisions\/107457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/37803"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=84546"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=84546"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=84546"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=84546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}