{"id":88964,"date":"2022-04-08T11:57:57","date_gmt":"2022-04-08T11:57:57","guid":{"rendered":"https:\/\/www.irdin.org.br\/site\/?post_type=product&#038;p=88964"},"modified":"2026-08-20T10:35:06","modified_gmt":"2026-08-20T13:35:06","slug":"9786588468241","status":"publish","type":"product","link":"https:\/\/www.irdin.org.br\/site\/produtos\/9786588468241\/","title":{"rendered":"Poemas al Inmaculado Coraz\u00f3n de Maria"},"content":{"rendered":"<p>Por medio de estos versos, las almas podr\u00e1n aproximarse al Inmaculado Coraz\u00f3n de Mar\u00eda, sentir Sua Santa Paz y ser impulsadas a recorrer el camino del apostolado de Cristo, de la vivencia del amor y del retorno al Coraz\u00f3n de Dios.<\/p>\n<p><a class=\"pdf\" href=\"\/pdf\/Poemas al Inmaculado Coraz\u00f3n de Mar\u00eda_WEB.pdf\" target=\"_blank\" rel=\"noopener\">Baixar Gratuitamente<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por medio de estos versos, las almas podr\u00e1n aproximarse al Inmaculado Coraz\u00f3n de Mar\u00eda, sentir Sua Santa Paz y ser<\/p>\n","protected":false},"featured_media":88965,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[33286,17972],"product_tag":[],"class_list":["post-88964","product","type-product","status-publish","has-post-thumbnail","product_cat-livro","product_cat-livros-livro","pa_autor-frei-elias-del-sagrado-corazon","pa_autor-madre-maria-shimani","pa_classe-do-produto-fisico","pa_codigo-de-barras-43974","pa_idioma-de-destino-espanhol","pa_idioma-de-origem-espanhol","pa_lancamento-yes","pa_midia-papel","pa_quantidade-de-paginas-43972","pa_quantidade-de-saldo-32994","pa_tipo-de-traducao-nao-classificado","first","instock","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/88964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/88964\/revisions"}],"predecessor-version":[{"id":106477,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product\/88964\/revisions\/106477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media\/88965"}],"wp:attachment":[{"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/media?parent=88964"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_brand?post=88964"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_cat?post=88964"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.irdin.org.br\/site\/wp-json\/wp\/v2\/product_tag?post=88964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}